{"id":13373,"date":"2024-10-29T12:20:04","date_gmt":"2024-10-29T12:20:04","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/vito-nicola-paradiso-danze-latino-americane-cd\/"},"modified":"2026-05-13T01:05:12","modified_gmt":"2026-05-13T01:05:12","slug":"vito-nicola-paradiso-danze-latino-americane-cd","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/vito-nicola-paradiso-danze-latino-americane-cd\/","title":{"rendered":"VITO NICOLA PARADISO DANZE LATINO AMERICANE + CD"},"content":{"rendered":"<p>Questa serie di dodici danze &egrave; il naturale prosieguo del progetto didattico La chitarra volante vol. 1 e 2, che gi&agrave; da qualche anno si sta imponendo nel panorama della didattica di base per chitarra.<\/p>\n<p>Si tratta di composizioni originali scritte nei diversi stili della musica latino americana, appositamente pensate per stimolare ed accrescere, nei giovani esecutori, la ricerca interpretativa, anche nelle risoluzioni di non semplici sequenze ritmiche, tipiche di questi generi. Ogni danza, infatti, &egrave; un omaggio allo stile dei compositori o dei generi tradizionali che hanno particolarmente connotato la storia di questa musica conosciuta e danzata in tutto il mondo: Heitor Villa-Lobos, Ariel Ramirez, Piazzolla, Gardel, Jobim, Toqui&ntilde;o, Cugat, Bonf&agrave;, ecc. Ognuno di essi ha ispirato, con le proprie sonorit&agrave; e peculiarit&agrave; ritmiche, i brani qui presentati.<\/p>\n<p>Scritte per due chitarre, queste danze possono essere eseguite anche con strumenti in Do o in Si bemolle e chitarra, grazie alle parti appositamente trascritte, collocate alla fine del volume. &Egrave; quindi possibile sostituire la prima chitarra con il violino, il flauto, il sax, la tromba o con strumenti a percussione determinate come il vibrafono o la marimba, quest&#8217;ultima particolarmente adatta, perch&eacute; tipica delle zone caraibiche.<\/p>\n<p>Tutti i brani sono accessibili ad un III corso strumentale, sia per le parti melodiche sia per l&#8217;accompagnamento.<\/p>\n<p>Il CD minus-one allegato, inoltre, offre non solo l&#8217;opportunit&agrave; di ascoltare i brani, ma anche di escludere (girando a destra o a sinistra la manopola &#8220;balance&#8221; dello stereo) una delle due chitarre: in questo modo sar&agrave; possibile eseguire a piacimento la melodia o l&#8217;accompagnamento, assieme a una delle due chitarre registrate sul CD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa serie di dodici danze &egrave; il naturale prosieguo del progetto didattico La chitarra volante vol. 1 e 2, che gi&agrave; da qualche anno si sta imponendo nel panorama della didattica di base per chitarra.<\/p>\n<p>Si tratta di composizioni originali scritte nei diversi stili della musica latino americana, appositamente pensate per stimolare ed accrescere, nei giovani esecutori, la ricerca interpretativa, anche nelle risoluzioni di non semplici sequenze ritmiche, tipiche di questi generi. Ogni danza, infatti, &egrave; un omaggio allo stile dei compositori o dei generi tradizionali che hanno particolarmente connotato la storia di questa musica conosciuta e danzata in tutto il mondo: Heitor Villa-Lobos, Ariel Ramirez, Piazzolla, Gardel, Jobim, Toqui&ntilde;o, Cugat, Bonf&agrave;, ecc. Ognuno di essi ha ispirato, con le proprie sonorit&agrave; e peculiarit&agrave; ritmiche, i brani qui presentati.<\/p>\n<p>Scritte per due chitarre, queste danze possono essere eseguite anche con strumenti in Do o in Si bemolle e chitarra, grazie alle parti appositamente trascritte, collocate alla fine del volume. &Egrave; quindi possibile sostituire la prima chitarra con il violino, il flauto, il sax, la tromba o con strumenti a percussione determinate come il vibrafono o la marimba, quest&#8217;ultima particolarmente adatta, perch&eacute; tipica delle zone caraibiche.<\/p>\n<p>Tutti i brani sono accessibili ad un III corso strumentale, sia per le parti melodiche sia per l&#8217;accompagnamento.<\/p>\n<p>Il CD minus-one allegato, inoltre, offre non solo l&#8217;opportunit&agrave; di ascoltare i brani, ma anche di escludere (girando a destra o a sinistra la manopola &#8220;balance&#8221; dello stereo) una delle due chitarre: in questo modo sar&agrave; possibile eseguire a piacimento la melodia o l&#8217;accompagnamento, assieme a una delle due chitarre registrate sul CD.<\/p>\n","protected":false},"featured_media":13372,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[547],"product_tag":[723],"class_list":{"0":"post-13373","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chitarra","7":"product_tag-dod","8":"desktop-align-left","9":"tablet-align-left","10":"mobile-align-left","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/13373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/13372"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=13373"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=13373"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=13373"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=13373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}