{"id":2474,"date":"2024-10-10T10:46:32","date_gmt":"2024-10-10T10:46:32","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/fender-player-plus-meteora-hh-mn-silverburst\/"},"modified":"2026-09-01T22:46:21","modified_gmt":"2026-09-01T22:46:21","slug":"fender-player-plus-meteora-hh-mn-silverburst","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/fender-player-plus-meteora-hh-mn-silverburst\/","title":{"rendered":"FENDER PLAYER PLUS METEORA HH MN SILVERBURST"},"content":{"rendered":"<p>Combinando l&#8217;innovativo design Fender con funzionalit&agrave; che mettono al centro l&#8217;esecutore e nuove straordinarie finiture, il Player Plus Meteora offre una suonabilit&agrave; imbattibile e uno stile inconfondibile. Un set di potenti pickup humbucking Fireball uniscono la quantit&agrave; perfetta di gain con un&#8217;eccezionale definizione delle note da una corda all&#8217;altra. Lo switch S-1 effettua lo &#8220;split&#8221; delle bobine, per timbriche single-coil dalla definizione cristallina. Lo scorrevole manico satinato con profilo Modern &#8220;C&#8221; si adatta alla tua mano come un guanto, con i suoi bordi smussati per il massimo comfort. Il raggio della tastiera da 12&#8243; e i 22 tasti medium jumbo garantiscono assoli e bend sempre perfettamente fluidi. Con una corsa sempre lineare e pronta, il tremolo ancorato in 2 punti crea i classici effetti di vibrato, mentre le meccaniche autobloccanti si caratterizzano per la stabilit&agrave; dell&#8217;accordatura e sostituzione delle corde rapide e semplici. Con il classico stile Fender, funzionalit&agrave; avanzate e nuove eccezionali finiture la Player Plus Meteora &egrave; lo strumento perfetto per incendiare la tua creativit&agrave; e per distinguerti dalla folla.<\/p>\n<p>Caratteristiche<br \/>Body: Ontano<br \/>Finitura: Lucida<br \/>Manico: Acero<br \/>Finitura: Uretano satinato con paletta lucida<br \/>Tastiera: Acero<br \/>Raggio: 12&#8243; (305mm)<br \/>Profilo: Modern &#8220;C&#8221;<br \/>Tasti: 20<br \/>Capotasto: Osso sintetico<br \/>Larghezza: 1.685&#8243; (42,8mm)<br \/>Segnatasti: Dot<br \/>Capotasto: Osso sintetico<br \/>Truss Rod: Azione singola<br \/>Pickup: 2x Fireball Humbucking<br \/>Controlli: Volume, 2x Tono<br \/>Selezione Aux: S-1 Switch sul Volume (per splittare la bobina)<br \/>Ponte: Tremolo sincronizzato 2-Punti con sellette in acciaio spazzolato<br \/>Manopole: Zigrinate con top piatto<br \/>Hardware: Nichel\/Cromo<br \/>Piastra del manico: 4-Bolt<br \/>Battipenna: 3-Strati, Nero\/Bianco\/Nero<br \/>Cover dei pickup: Cromate<br \/>Reggitracolla: Vintage-Style<br \/>Meccaniche: Deluxe locking sigillate<br \/>Made in Mexico<br \/>Finitura: Silverburst<br \/>Bag:SI\/Yes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Combinando l&#8217;innovativo design Fender con funzionalit&agrave; che mettono al centro l&#8217;esecutore e nuove straordinarie finiture, il Player Plus Meteora offre una suonabilit&agrave; imbattibile e uno stile inconfondibile. Un set di potenti pickup humbucking Fireball uniscono la quantit&agrave; perfetta di gain con un&#8217;eccezionale definizione delle note da una corda all&#8217;altra. Lo switch S-1 effettua lo &#8220;split&#8221; [&hellip;]<\/p>\n","protected":false},"featured_media":2469,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[387],"product_tag":[733],"class_list":["post-2474","product","type-product","status-publish","has-post-thumbnail","product_cat-chitarre-elettriche","product_tag-fender","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/2474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/2469"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=2474"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=2474"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=2474"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=2474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}