{"id":27538,"date":"2025-12-30T08:07:48","date_gmt":"2025-12-30T08:07:48","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/adam-t7v\/"},"modified":"2026-05-13T00:06:49","modified_gmt":"2026-05-13T00:06:49","slug":"adam-t7v","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/adam-t7v\/","title":{"rendered":"ADAM T7V"},"content":{"rendered":"<p>STUDIO MONITOR NEARFIELD BIAMPLIFICATO 7&#8243; 70W<br \/>Il T7V \u00e8 un monitor da studio a due vie progettato per l&#8217;uso verticale in applicazioni nearfield. Il T7V \u00e8 dotato di un woofer da 7&#8243; che fornisce un&#8217;estensione dei bassi fino a 39Hz, mentre il diaframma del tweeter U-ART fornisce una risposta ad alta frequenza elevata ed estesa fino a 25 kHz, praticamente inaudita nei monitor in questa fascia di prezzo. Il tweeter U-ART \u00e8 montato su una guida d&#8217;onda di precisione con le stesse caratteristiche di controllo della dispersione della guida d&#8217;onda HPS (High Frequency Propagation) utilizzata nei monitor da studio di punta della Serie S di ADAM Audio. La dispersione altamente uniforme delle alte frequenze della guida d&#8217;onda fornisce uno sweet spot incredibilmente ampio che ti libera dall&#8217;essere incollato a una posizione del mix durante il lavoro. Sul lato posteriore del cabinet smussato del T7V, una porta bass reflex rear-porting si unisce a una robusta piastra posteriore in metallo che ospita le connessioni di ingresso analogiche. Il tweeter U-ART \u00e8 alimentato da un amplificatore in classe D da 20W, mentre un amplificatore in classe D da 50W serve il woofer. Questi nuovi powerhouse producono una SPL massima impressionante di 110dB per coppia. L&#8217;ampia risposta in frequenza, l&#8217;elevata gamma dinamica, l&#8217;eccellente risposta ai transienti, l&#8217;ampio sweet spot e le piccole impronte rendono il T7V perfettamente adatto per l&#8217;uso in sale di controllo di piccole dimensioni o per la post-produzione video e la produzione broadcast. Il subwoofer ADAM Sub8 \u00e8 l&#8217;abbinamento perfetto per integrare il T7V ed estendere le funzionalit\u00e0 di monitoraggio nelle basse frequenze.<br \/>Caratteristiche<br \/>Driver LF: Woofer da 7&#8243;<br \/>Driver HF: Tweeter a nastro U-ART da 1,9&#8243;<br \/>2x Amplificatore in Classe D: Woofer da 50W RMS, Tweeter da 20W RMS<br \/>Intervallo di frequenza: 39Hz &#8211; 25kHz<br \/>Frequenza di crossover: 2,6kHz<br \/>Spl max: 110 dB (1m \/ coppia)<br \/>Porta posteriore: Bass reflex<br \/>Connessioni: Input di linea XLR e RCA<br \/>Dimensioni: 210 x 347 x 293mm<br \/>Peso: 7,1kg<br \/>NOTA: Il prezzo si riferisce alla cassa SINGOLA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STUDIO MONITOR NEARFIELD BIAMPLIFICATO 7&#8243; 70WIl T7V \u00e8 un monitor da studio a due vie progettato per l&#8217;uso verticale in applicazioni nearfield. Il T7V \u00e8 dotato di un woofer da 7&#8243; che fornisce un&#8217;estensione dei bassi fino a 39Hz, mentre il diaframma del tweeter U-ART fornisce una risposta ad alta frequenza elevata ed estesa fino [&hellip;]<\/p>\n","protected":false},"featured_media":27539,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[663],"product_tag":[],"class_list":{"0":"post-27538","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-studio-monitor","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/27538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/27539"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=27538"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=27538"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=27538"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=27538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}