{"id":3669,"date":"2024-10-10T17:50:48","date_gmt":"2024-10-10T17:50:48","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/oqan-qp100-pianoforte-digitale-88-tasti-nero\/"},"modified":"2026-05-12T22:03:04","modified_gmt":"2026-05-12T22:03:04","slug":"oqan-qp100-pianoforte-digitale-88-tasti-nero","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/oqan-qp100-pianoforte-digitale-88-tasti-nero\/","title":{"rendered":"OQAN QP100  PIANOFORTE DIGITALE 88 TASTI NERO"},"content":{"rendered":"<p>PIANOFORTE DIGITALE 88 TASTI PESATI NERO<br \/> Oqan QP100, uno strumento che si distingue per l&#8217;eccezionale rapporto qualit&agrave;-prezzo. Con una tastiera pesata a 88 tasti che offre un&#8217;esperienza autentica e una struttura che simula la sensazione di un pianoforte acustico, questo modello ti invita a esplorare un&#8217;ampia variet&agrave; di stili musicali grazie ai suoi impressionanti 169 suoni e 88 brani demo.<br \/>Una delle caratteristiche principali del QP100 &egrave; la possibilit&agrave; di memorizzare fino a 2 preset, rendendo facile l&#8217;accesso ai tuoi suoni preferiti con un semplice tocco. La batteria ricaricabile, un&#8217;altra qualit&agrave; unica del QP100, aggiunge grande comodit&agrave; in termini di mobilit&agrave;, consentendo di utilizzarlo sempre e ovunque senza dover ricorrere a prese di corrente o batterie.<br \/>Inoltre, il QP100 offre una connettivit&agrave; completa che comprende uscite audio, ingressi di linea e microfonici, una porta USB\/MIDI che lo rende un controller MIDI capace e la possibilit&agrave; di riprodurre file MP3 da una chiavetta USB.<br \/>Naturalmente, il QP100 dispone di funzioni di registrazione e di una serie di effetti, come il riverbero, il vibrato e il sustain, che estendono le note senza bisogno di un pedale. Dotato di un sistema di altoparlanti da 2 x 25W di potenza, di un pedale sustain e di una pratica custodia per il trasporto inclusi nella confezione, l&#8217;Oqan QP100 si distingue come una delle migliori opzioni nella categoria dei pianoforti digitali compatti.<br \/>Caratteristiche principali:<br \/>88 tasti pesati<br \/>Tastiera testurizzata<br \/>169 suoni<br \/>88 canzoni demo<br \/>2 memorie per i suoni favoriti<br \/>Batteria ricaricabile<br \/>USB\/MIDI<br \/>Lettore MP3<br \/>Funzione di registrazione<br \/>Effetti riverbero \/ vibrato \/ sustain<br \/>Uscita audio<br \/>Ingresso di linea e microfono<br \/>Potenza 2 x 25W<br \/>Dimensioni: 129,5 x 25 x 10 cm<br \/>Peso: 12,6 kg<br \/>Pedale di sustain e borsa per il trasporto inclusi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIANOFORTE DIGITALE 88 TASTI PESATI NERO<br \/> Oqan QP100, uno strumento che si distingue per l&#8217;eccezionale rapporto qualit&agrave;-prezzo. Con una tastiera pesata a 88 tasti che offre un&#8217;esperienza autentica e una struttura che simula la sensazione di un pianoforte acustico, questo modello ti invita a esplorare un&#8217;ampia variet&agrave; di stili musicali grazie ai suoi impressionanti 169 suoni e 88 brani demo.<br \/>Una delle caratteristiche principali del QP100 &egrave; la possibilit&agrave; di memorizzare fino a 2 preset, rendendo facile l&#8217;accesso ai tuoi suoni preferiti con un semplice tocco. La batteria ricaricabile, un&#8217;altra qualit&agrave; unica del QP100, aggiunge grande comodit&agrave; in termini di mobilit&agrave;, consentendo di utilizzarlo sempre e ovunque senza dover ricorrere a prese di corrente o batterie.<br \/>Inoltre, il QP100 offre una connettivit&agrave; completa che comprende uscite audio, ingressi di linea e microfonici, una porta USB\/MIDI che lo rende un controller MIDI capace e la possibilit&agrave; di riprodurre file MP3 da una chiavetta USB.<br \/>Naturalmente, il QP100 dispone di funzioni di registrazione e di una serie di effetti, come il riverbero, il vibrato e il sustain, che estendono le note senza bisogno di un pedale. Dotato di un sistema di altoparlanti da 2 x 25W di potenza, di un pedale sustain e di una pratica custodia per il trasporto inclusi nella confezione, l&#8217;Oqan QP100 si distingue come una delle migliori opzioni nella categoria dei pianoforti digitali compatti.<br \/>Caratteristiche principali:<br \/>88 tasti pesati<br \/>Tastiera testurizzata<br \/>169 suoni<br \/>88 canzoni demo<br \/>2 memorie per i suoni favoriti<br \/>Batteria ricaricabile<br \/>USB\/MIDI<br \/>Lettore MP3<br \/>Funzione di registrazione<br \/>Effetti riverbero \/ vibrato \/ sustain<br \/>Uscita audio<br \/>Ingresso di linea e microfono<br \/>Potenza 2 x 25W<br \/>Dimensioni: 129,5 x 25 x 10 cm<br \/>Peso: 12,6 kg<br \/>Pedale di sustain e borsa per il trasporto inclusi<\/p>\n","protected":false},"featured_media":3668,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[675],"product_tag":[],"class_list":{"0":"post-3669","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pianoforti-digitali","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/3669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/3668"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=3669"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=3669"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=3669"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=3669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}