{"id":4458,"date":"2024-10-11T10:36:58","date_gmt":"2024-10-11T10:36:58","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/mooer-micro-looper-pedal-usato\/"},"modified":"2026-09-02T00:27:07","modified_gmt":"2026-09-02T00:27:07","slug":"mooer-micro-looper-pedal-usato","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/mooer-micro-looper-pedal-usato\/","title":{"rendered":"MOOER MICRO LOOPER PEDAL &#8211; USATO &#8211;"},"content":{"rendered":"<p>Il Micro Looper eredita le dimensioni mini della Serie Micro. Record, playback, stop, overdub e delete, tutte queste funzioni possono essere controllate da un unico pedale. Questo ti d&agrave; una esperienza di funzionamento facile e diretta. Micro Looper ha fino a 30 minuti di registrazione e tempi di sovraincisione illimitati. &Egrave; possibile concentrarsi sulla musica e non preoccuparsi di altri problemi.<br \/>Caratteristiche principali<\/p>\n<p>True Bypass: Quando Micro Looper &egrave; in bypass non influenza il segnale originale<br \/>Tempo di registrazione: Micro Looper ha fino a 30 minuti di registrazione, abbastanza per registrare le tue canzoni<br \/>Tempo si sovraincisione illimitato: Micro Looper non ha limite massimo per i tempi sovraincisione<br \/>Alta qualit&agrave; del suono: L&#8217;utilizzo di componenti elettronici di alta qualit&agrave; garantiscono un segnale audio di riproduzione chiaro come &egrave; stato registrato<br \/>Dimensioni Mini: Eredita la dimensione dei pedali della Serie Micro<br \/>Controllo Level: Questa piccola manopola &egrave; in grado di controllare il volume del loop. Non senti il tuo assolo? Abbassare un p&ograve; il volume<br \/>Facilit&agrave; d&#8217;uso: Stop \/ Delete \/ Redo, tutte queste funzioni sono controllate da un solo pedale<br \/>Funzione di salvataggio Loop: Micro Looper salva automaticamente tutti i dati registrazioni dei loop quando viene &egrave; spento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Micro Looper eredita le dimensioni mini della Serie Micro. Record, playback, stop, overdub e delete, tutte queste funzioni possono essere controllate da un unico pedale. Questo ti d&agrave; una esperienza di funzionamento facile e diretta. Micro Looper ha fino a 30 minuti di registrazione e tempi di sovraincisione illimitati. &Egrave; possibile concentrarsi sulla musica e non preoccuparsi di altri problemi.<br \/>Caratteristiche principali<\/p>\n<p>True Bypass: Quando Micro Looper &egrave; in bypass non influenza il segnale originale<br \/>Tempo di registrazione: Micro Looper ha fino a 30 minuti di registrazione, abbastanza per registrare le tue canzoni<br \/>Tempo si sovraincisione illimitato: Micro Looper non ha limite massimo per i tempi sovraincisione<br \/>Alta qualit&agrave; del suono: L&#8217;utilizzo di componenti elettronici di alta qualit&agrave; garantiscono un segnale audio di riproduzione chiaro come &egrave; stato registrato<br \/>Dimensioni Mini: Eredita la dimensione dei pedali della Serie Micro<br \/>Controllo Level: Questa piccola manopola &egrave; in grado di controllare il volume del loop. Non senti il tuo assolo? Abbassare un p&ograve; il volume<br \/>Facilit&agrave; d&#8217;uso: Stop \/ Delete \/ Redo, tutte queste funzioni sono controllate da un solo pedale<br \/>Funzione di salvataggio Loop: Micro Looper salva automaticamente tutti i dati registrazioni dei loop quando viene &egrave; spento<\/p>\n","protected":false},"featured_media":4457,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[126],"product_tag":[751],"class_list":["post-4458","product","type-product","status-publish","has-post-thumbnail","product_cat-usato","product_tag-mooer","desktop-align-left","tablet-align-left","mobile-align-left","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/4458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/4457"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=4458"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=4458"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=4458"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=4458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}