{"id":6809,"date":"2024-10-28T09:48:04","date_gmt":"2024-10-28T09:48:04","guid":{"rendered":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/mooer-preamp-live\/"},"modified":"2026-09-01T23:09:03","modified_gmt":"2026-09-01T23:09:03","slug":"mooer-preamp-live","status":"publish","type":"product","link":"https:\/\/gigionestrumentimusicali.it\/index.php\/product\/mooer-preamp-live\/","title":{"rendered":"MOOER PREAMP LIVE"},"content":{"rendered":"<p>Preamplificatore multicanale per chitarra elettrica<br \/>* Contiene 12 canali di preamplificazione indipendenti divisi in 3 banchi di 4 preset, richiamabili via 4 footswitch frontali. I controlli di editing sono immediati ed intuitivi come in un normale amplificatore.<br \/>* 50 preamplificatori, 30 cabinet ed 11 microfoni diversi tra cui scegliere i 12 preset definitivi.<br \/>* Effetti boost e noise gate modificabili Pre \/ Post per ciascun canale.<br \/>* Controlli globali facilmente accessibili per una rapida configurazione in diverse situazioni live.<br \/>* Simulazione di cassa opzionale, indipendente per ciascuna uscita.<br \/>* Caricamento IR tramite software di supporto e App Mobile Mooer Preamp Live dedicata.<br \/>* Loop effetti completamente programmabili con modalit&agrave; seriale e A \/ B. Metodo 4-cavi per il collegamento con effetti esterni o la combinazione con il proprio amplificatore testata o combo. <br \/>* FunzioneTone Capture per campionare le caratteristiche tonali di amplificatori reali, e creare nuovi modelli digitali di preamplificatore.<br \/>* Uscita cuffie dedicata.<br \/>* Midi In e Midi Out completamente mappabili per l&#8217;integrazione con altre apparecchiature.<br \/>* USB e Bluetooth per il collegamento a Pc, Mac e App Mobile Mooer Preamp Live dedicata per editing approfondito e selezione dell&#8217;amplificatore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preamplificatore multicanale per chitarra elettrica<br \/>* Contiene 12 canali di preamplificazione indipendenti divisi in 3 banchi di 4 preset, richiamabili via 4 footswitch frontali. I controlli di editing sono immediati ed intuitivi come in un normale amplificatore.<br \/>* 50 preamplificatori, 30 cabinet ed 11 microfoni diversi tra cui scegliere i 12 preset definitivi.<br \/>* Effetti boost e noise gate modificabili Pre \/ Post per ciascun canale.<br \/>* Controlli globali facilmente accessibili per una rapida configurazione in diverse situazioni live.<br \/>* Simulazione di cassa opzionale, indipendente per ciascuna uscita.<br \/>* Caricamento IR tramite software di supporto e App Mobile Mooer Preamp Live dedicata.<br \/>* Loop effetti completamente programmabili con modalit&agrave; seriale e A \/ B. Metodo 4-cavi per il collegamento con effetti esterni o la combinazione con il proprio amplificatore testata o combo. <br \/>* FunzioneTone Capture per campionare le caratteristiche tonali di amplificatori reali, e creare nuovi modelli digitali di preamplificatore.<br \/>* Uscita cuffie dedicata.<br \/>* Midi In e Midi Out completamente mappabili per l&#8217;integrazione con altre apparecchiature.<br \/>* USB e Bluetooth per il collegamento a Pc, Mac e App Mobile Mooer Preamp Live dedicata per editing approfondito e selezione dell&#8217;amplificatore.<\/p>\n","protected":false},"featured_media":6803,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[371],"product_tag":[751],"class_list":["post-6809","product","type-product","status-publish","has-post-thumbnail","product_cat-preamplificatori","product_tag-mooer","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product\/6809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media\/6803"}],"wp:attachment":[{"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/media?parent=6809"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_brand?post=6809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_cat?post=6809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gigionestrumentimusicali.it\/index.php\/wp-json\/wp\/v2\/product_tag?post=6809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}